{"id":15712,"date":"2026-05-13T17:02:44","date_gmt":"2026-05-13T17:02:44","guid":{"rendered":"https:\/\/forumenfermagem.org\/site\/associacao-diz-que-medicos-de-familia-saem-penalizados-pelo-aumento-do-preco-dos-exames-nos-convencionados\/"},"modified":"2026-05-13T17:02:44","modified_gmt":"2026-05-13T17:02:44","slug":"associacao-diz-que-medicos-de-familia-saem-penalizados-pelo-aumento-do-preco-dos-exames-nos-convencionados","status":"publish","type":"post","link":"https:\/\/forumenfermagem.org\/site\/associacao-diz-que-medicos-de-familia-saem-penalizados-pelo-aumento-do-preco-dos-exames-nos-convencionados\/","title":{"rendered":"Associa\u00e7\u00e3o diz que m\u00e9dicos de fam\u00edlia saem penalizados pelo aumento do pre\u00e7o dos exames nos convencionados"},"content":{"rendered":"<div>Associa\u00e7\u00e3o Nacional das Unidades de Sa\u00fade Familiar defende que poupan\u00e7a seria maior se m\u00e9dicos tivessem acesso autom\u00e1tico \u00e0 lista de medicamentos ordenados do mais barato para o mais caro.<\/div>\n<p>\u00a0<\/p>\n<p>\n<a href=\"https:\/\/www.publico.pt\/2026\/05\/13\/sociedade\/noticia\/associacao-medicos-familia-saem-penalizados-aumento-preco-exames-convencionados-2174470\" class=\"info\" rel=\"nofollow noopener\" target=\"_blank\">Leia na \u00edntegra em <b>Publico.pt<b><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Associa\u00e7\u00e3o Nacional das Unidades de Sa\u00fade Familiar defende que poupan\u00e7a seria maior se m\u00e9dicos tivessem acesso autom\u00e1tico \u00e0 lista de medicamentos ordenados do mais barato para o mais caro. \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15713,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-15712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"_links":{"self":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/15712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/comments?post=15712"}],"version-history":[{"count":0,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/15712\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media\/15713"}],"wp:attachment":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media?parent=15712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/categories?post=15712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/tags?post=15712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}