{"id":15694,"date":"2026-05-13T10:13:39","date_gmt":"2026-05-13T10:13:39","guid":{"rendered":"https:\/\/forumenfermagem.org\/site\/unidade-local-de-saude-da-regiao-de-aveiro-epe-procedimento-concursal-para-constituicao-de-bolsa-de-5\/"},"modified":"2026-05-13T10:13:39","modified_gmt":"2026-05-13T10:13:39","slug":"unidade-local-de-saude-da-regiao-de-aveiro-epe-procedimento-concursal-para-constituicao-de-bolsa-de-5","status":"publish","type":"post","link":"https:\/\/forumenfermagem.org\/site\/unidade-local-de-saude-da-regiao-de-aveiro-epe-procedimento-concursal-para-constituicao-de-bolsa-de-5\/","title":{"rendered":"Unidade Local de Sa\u00fade da Regi\u00e3o de Aveiro, EPE Procedimento concursal para constitui\u00e7\u00e3o de bolsa de  &#8230;"},"content":{"rendered":"<div>Unidade Local de Sa\u00fade da Regi\u00e3o de Aveiro, EPE Procedimento concursal para constitui\u00e7\u00e3o de bolsa de recrutamento para a categoria de enfermeiro especialista.<\/p>\n<p>    Aviso (extrato) n.\u00ba 11030\/2026\/2  &#8211;  Di\u00e1rio da Rep\u00fablica n.\u00ba 92\/2026, S\u00e9rie II de 2026-05-13<\/p><\/div>\n<p>\u00a0<\/p>\n<p>\n<a href=\"https:\/\/diariodarepublica.pt\/dr\/detalhe\/aviso-extrato\/11030-1121025534\" class=\"info\" rel=\"nofollow noopener\" target=\"_blank\">Leia na \u00edntegra em <b>Di\u00e1rio da Rep\u00fablica<b><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unidade Local de Sa\u00fade da Regi\u00e3o de Aveiro, EPE Procedimento concursal para constitui\u00e7\u00e3o de bolsa de recrutamento para a categoria de enfermeiro especialista. Aviso (extrato) n.\u00ba 11030\/2026\/2 &#8211; Di\u00e1rio da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1122],"tags":[1123],"class_list":["post-15694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diario-da-republica","tag-diario-da-republica"],"_links":{"self":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/15694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/comments?post=15694"}],"version-history":[{"count":0,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/15694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media\/3664"}],"wp:attachment":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media?parent=15694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/categories?post=15694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/tags?post=15694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}