{"id":15463,"date":"2026-05-06T09:02:27","date_gmt":"2026-05-06T09:02:27","guid":{"rendered":"https:\/\/forumenfermagem.org\/site\/surto-de-hantavirus-espanha-aceita-acolher-medico-do-cruzeiro-que-se-encontra-em-estado-grave\/"},"modified":"2026-05-06T09:02:27","modified_gmt":"2026-05-06T09:02:27","slug":"surto-de-hantavirus-espanha-aceita-acolher-medico-do-cruzeiro-que-se-encontra-em-estado-grave","status":"publish","type":"post","link":"https:\/\/forumenfermagem.org\/site\/surto-de-hantavirus-espanha-aceita-acolher-medico-do-cruzeiro-que-se-encontra-em-estado-grave\/","title":{"rendered":"Surto de hantav\u00edrus: Espanha aceita acolher m\u00e9dico do cruzeiro que se encontra em estado grave"},"content":{"rendered":"<div>O governo espanhol aceitou o transporte urgente para as Can\u00e1rias do m\u00e9dico do MV Hondius, que se encontra em estado grave devido ao hantav\u00edrus, no \u00e2mbito da opera\u00e7\u00e3o coordenada com a OMS e a UE para prestar assist\u00eancia ao navio, que navega atualmente nas \u00e1guas de Cabo Verde.<\/div>\n<p>\u00a0<\/p>\n<p>\n<a href=\"https:\/\/pt.euronews.com\/saude\/2026\/05\/06\/surto-de-hantavirus-espanha-aceita-acolher-medico-do-cruzeiro-que-se-encontra-em-estado-gr\" class=\"info\" rel=\"nofollow noopener\" target=\"_blank\">Leia na \u00edntegra em <b>EuroNews.com<b><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo espanhol aceitou o transporte urgente para as Can\u00e1rias do m\u00e9dico do MV Hondius, que se encontra em estado grave devido ao hantav\u00edrus, no \u00e2mbito da opera\u00e7\u00e3o coordenada com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-15463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"_links":{"self":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/15463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/comments?post=15463"}],"version-history":[{"count":0,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/15463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media\/15464"}],"wp:attachment":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media?parent=15463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/categories?post=15463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/tags?post=15463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}