{"id":15461,"date":"2026-05-06T07:02:52","date_gmt":"2026-05-06T07:02:52","guid":{"rendered":"https:\/\/forumenfermagem.org\/site\/obstetricia-urgencias-da-peninsula-de-setubal-estiveram-um-terco-do-tempo-fechadas\/"},"modified":"2026-05-06T07:02:52","modified_gmt":"2026-05-06T07:02:52","slug":"obstetricia-urgencias-da-peninsula-de-setubal-estiveram-um-terco-do-tempo-fechadas","status":"publish","type":"post","link":"https:\/\/forumenfermagem.org\/site\/obstetricia-urgencias-da-peninsula-de-setubal-estiveram-um-terco-do-tempo-fechadas\/","title":{"rendered":"Obstetr\u00edcia: urg\u00eancias da pen\u00ednsula de Set\u00fabal estiveram um ter\u00e7o do tempo fechadas"},"content":{"rendered":"<div>Regulador da Sa\u00fade, que analisou per\u00edodo entre Outubro de 2024 e Novembro de 2025, diz que constrangimentos decorrentes de limita\u00e7\u00f5es dos prestadores \u201cse reflectem em restri\u00e7\u00f5es efectivas ao acesso\u201d.<\/div>\n<p>\u00a0<\/p>\n<p>\n<a href=\"https:\/\/www.publico.pt\/2026\/05\/06\/sociedade\/noticia\/obstetricia-urgencias-peninsula-setubal-terco-tempo-fechadas-2173619\" class=\"info\" rel=\"nofollow noopener\" target=\"_blank\">Leia na \u00edntegra em <b>Publico.pt<b><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Regulador da Sa\u00fade, que analisou per\u00edodo entre Outubro de 2024 e Novembro de 2025, diz que constrangimentos decorrentes de limita\u00e7\u00f5es dos prestadores \u201cse reflectem em restri\u00e7\u00f5es efectivas ao acesso\u201d. \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-15461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"_links":{"self":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/15461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/comments?post=15461"}],"version-history":[{"count":0,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/15461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media\/15462"}],"wp:attachment":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media?parent=15461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/categories?post=15461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/tags?post=15461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}