{"id":14297,"date":"2026-02-09T20:03:20","date_gmt":"2026-02-09T20:03:20","guid":{"rendered":"https:\/\/forumenfermagem.org\/site\/a-saude-na-catastrofe\/"},"modified":"2026-02-09T20:03:20","modified_gmt":"2026-02-09T20:03:20","slug":"a-saude-na-catastrofe","status":"publish","type":"post","link":"https:\/\/forumenfermagem.org\/site\/a-saude-na-catastrofe\/","title":{"rendered":"A sa\u00fade na cat\u00e1strofe"},"content":{"rendered":"<div>Os profissionais de sa\u00fade t\u00eam a obriga\u00e7\u00e3o \u00e9tica de alertar para o impacto das altera\u00e7\u00f5es ambientais na sa\u00fade humana, fatores que j\u00e1 s\u00e3o respons\u00e1veis por uma em cada quatro mortes a n\u00edvel global. Opini\u00e3o de Lu\u00eds Campos<\/div>\n<p>\u00a0<\/p>\n<p>\n<a href=\"https:\/\/www.publico.pt\/2026\/02\/09\/opiniao\/opiniao\/saude-catastrofe-2164218\" class=\"info\" rel=\"nofollow noopener\" target=\"_blank\">Leia na \u00edntegra em <b>Publico.pt<b><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os profissionais de sa\u00fade t\u00eam a obriga\u00e7\u00e3o \u00e9tica de alertar para o impacto das altera\u00e7\u00f5es ambientais na sa\u00fade humana, fatores que j\u00e1 s\u00e3o respons\u00e1veis por uma em cada quatro mortes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-14297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"_links":{"self":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/14297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/comments?post=14297"}],"version-history":[{"count":0,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/14297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media\/14298"}],"wp:attachment":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media?parent=14297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/categories?post=14297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/tags?post=14297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}