{"id":12451,"date":"2025-11-17T14:03:17","date_gmt":"2025-11-17T14:03:17","guid":{"rendered":"https:\/\/forumenfermagem.org\/site\/testamentos-vitais-aumentaram-89-num-ano-para-os-44-817-e-quase-um-nao-crescimento\/"},"modified":"2025-11-17T14:03:17","modified_gmt":"2025-11-17T14:03:17","slug":"testamentos-vitais-aumentaram-89-num-ano-para-os-44-817-e-quase-um-nao-crescimento","status":"publish","type":"post","link":"https:\/\/forumenfermagem.org\/site\/testamentos-vitais-aumentaram-89-num-ano-para-os-44-817-e-quase-um-nao-crescimento\/","title":{"rendered":"Testamentos vitais aumentaram 8,9% num ano para os 44.817. \u00c9 quase \u201cum n\u00e3o crescimento\u201d"},"content":{"rendered":"<div>Conselho de \u00c9tica para as Ci\u00eancias da Vida vai reunir-se nesta semana para analisar as raz\u00f5es da modesta ades\u00e3o dos portugueses ao testamento vital e procurar formas de o tornar \u201cmais pr\u00f3ximo\u201d.<\/div>\n<p>\u00a0<\/p>\n<p>\n<a href=\"https:\/\/www.publico.pt\/2025\/11\/17\/sociedade\/noticia\/testamentos-vitais-aumentaram-89-ano-44817-quase-nao-crescimento-2154794\" class=\"info\" rel=\"nofollow noopener\" target=\"_blank\">Leia na \u00edntegra em <b>Publico.pt<b><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conselho de \u00c9tica para as Ci\u00eancias da Vida vai reunir-se nesta semana para analisar as raz\u00f5es da modesta ades\u00e3o dos portugueses ao testamento vital e procurar formas de o tornar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12452,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-12451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"_links":{"self":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/12451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/comments?post=12451"}],"version-history":[{"count":0,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts\/12451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media\/12452"}],"wp:attachment":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/media?parent=12451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/categories?post=12451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/tags?post=12451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}