{"id":44,"count":0,"description":"","link":"https:\/\/forumenfermagem.org\/site\/categoria\/arquivo\/reportagens\/","name":"Reportagens","slug":"reportagens","taxonomy":"category","parent":1070,"meta":[],"_links":{"self":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/categories\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/categories\/1070"}],"wp:post_type":[{"href":"https:\/\/forumenfermagem.org\/site\/wp-json\/wp\/v2\/posts?categories=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}